{"id":11366,"date":"2023-07-13T10:24:34","date_gmt":"2023-07-13T10:24:34","guid":{"rendered":"https:\/\/www.terabyteplus.com\/?p=11366"},"modified":"2024-02-15T16:45:25","modified_gmt":"2024-02-15T09:45:25","slug":"t-group-academy-%e0%b8%9e%e0%b8%b5%e0%b9%88%e0%b8%aa%e0%b8%ad%e0%b8%99%e0%b8%99%e0%b9%89%e0%b8%ad%e0%b8%87","status":"publish","type":"post","link":"https:\/\/www.terabyteplus.com\/en\/t-group-academy-%e0%b8%9e%e0%b8%b5%e0%b9%88%e0%b8%aa%e0%b8%ad%e0%b8%99%e0%b8%99%e0%b9%89%e0%b8%ad%e0%b8%87\/","title":{"rendered":"T.Group Academy: \u0e1e\u0e35\u0e48\u0e2a\u0e2d\u0e19\u0e19\u0e49\u0e2d\u0e07               Professional Presentation Skill (Ep.1)"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"11366\" class=\"elementor elementor-11366\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-71e12e4b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"71e12e4b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3017b75e\" data-id=\"3017b75e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-37ecfdd6 elementor-widget elementor-widget-text-editor\" data-id=\"37ecfdd6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.18.0 - 20-12-2023 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<!-- wp:paragraph -->\n<p>\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21 T.Group Academy: \u0e1e\u0e35\u0e48\u0e2a\u0e2d\u0e19\u0e19\u0e49\u0e2d\u0e07<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 13 \u0e01\u0e23\u0e01\u0e0e\u0e32\u0e04\u0e21 2566 \u0e17\u0e35\u0e48\u0e1c\u0e48\u0e32\u0e19\u0e21\u0e32 \u0e42\u0e14\u0e22 topic \u0e43\u0e19\u0e04\u0e23\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e43\u0e19\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 Professional Presentation Skill (Ep.1) \u00a0\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e20\u0e32\u0e22\u0e43\u0e19\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23 \u00a0\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e2a\u0e39\u0e48\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>\u0e19\u0e33\u0e17\u0e31\u0e1e\u0e42\u0e14\u0e22 \u00a0\u0e17\u0e35\u0e21\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e2f \u0e17\u0e35\u0e48\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e41\u0e1a\u0e48\u0e07\u0e1b\u0e31\u0e19\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e41\u0e25\u0e30\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04\u0e17\u0e35\u0e48\u0e2a\u0e33\u0e04\u0e31\u0e0d \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e34\u0e14\u0e2d\u0e07\u0e04\u0e4c\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e41\u0e25\u0e30\u0e19\u0e33\u0e44\u0e1b\u0e15\u0e48\u0e2d\u0e22\u0e2d\u0e14\u0e43\u0e19\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e21\u0e35\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e14<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>\u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e02\u0e2d\u0e02\u0e2d\u0e1a\u0e04\u0e38\u0e13\u0e17\u0e35\u0e21\u0e07\u0e32\u0e19\u0e04\u0e19\u0e01\u0e25\u0e49\u0e32\u0e04\u0e37\u0e19\u0e16\u0e34\u0e48\u0e19\u00a0 \u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e43\u0e2b\u0e49\u0e01\u0e32\u0e23\u0e15\u0e49\u0e2d\u0e19\u0e23\u0e31\u0e1a \u0e40\u0e2d\u0e37\u0e49\u0e2d\u0e40\u0e1f\u0e37\u0e49\u0e2d\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48 \u0e2d\u0e33\u0e19\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e14\u0e27\u0e01\u0e14\u0e49\u0e32\u0e19\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e25\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e33\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e08\u0e32\u0e01\u0e1e\u0e37\u0e0a\u0e1c\u0e31\u0e01\u0e1b\u0e25\u0e2d\u0e14\u0e2a\u0e32\u0e23\u0e1e\u0e34\u0e29\u0e43\u0e2b\u0e49\u0e1e\u0e27\u0e01\u0e40\u0e23\u0e32\u0e44\u0e14\u0e49\u0e17\u0e32\u0e19\u0e01\u0e31\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e14\u0e35 @ Tree Eco Working Space (\u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e23\u0e32\u0e21\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e32 \u0e16\u0e19\u0e19\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e32) \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e43\u0e19\u0e04\u0e23\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e04\u0e48\u0e30<\/p>\n<!-- \/wp:paragraph -->\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21 T.Group Academy: \u0e1e\u0e35\u0e48\u0e2a\u0e2d\u0e19\u0e19\u0e49\u0e2d\u0e07 \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 13 \u0e01\u0e23\u0e01\u0e0e\u0e32\u0e04\u0e21 2566 \u0e17\u0e35\u0e48\u0e1c\u0e48\u0e32\u0e19\u0e21\u0e32 \u0e42\u0e14\u0e22 topic \u0e43\u0e19\u0e04\u0e23\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e43\u0e19\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 Professional Presentation Skill (Ep.1) \u00a0\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e20\u0e32\u0e22\u0e43\u0e19\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23 \u00a0\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e2a\u0e39\u0e48\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08 \u0e19\u0e33\u0e17\u0e31\u0e1e\u0e42\u0e14\u0e22 \u00a0\u0e17\u0e35\u0e21\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e2f \u0e17\u0e35\u0e48\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e41\u0e1a\u0e48\u0e07\u0e1b\u0e31\u0e19\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e41\u0e25\u0e30\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04\u0e17\u0e35\u0e48\u0e2a\u0e33\u0e04\u0e31\u0e0d \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e34\u0e14\u0e2d\u0e07\u0e04\u0e4c\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e41\u0e25\u0e30\u0e19\u0e33\u0e44\u0e1b\u0e15\u0e48\u0e2d\u0e22\u0e2d\u0e14\u0e43\u0e19\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e21\u0e35\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e02\u0e2d\u0e02\u0e2d\u0e1a\u0e04\u0e38\u0e13\u0e17\u0e35\u0e21\u0e07\u0e32\u0e19\u0e04\u0e19\u0e01\u0e25\u0e49\u0e32\u0e04\u0e37\u0e19\u0e16\u0e34\u0e48\u0e19\u00a0 \u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e43\u0e2b\u0e49\u0e01\u0e32\u0e23\u0e15\u0e49\u0e2d\u0e19\u0e23\u0e31\u0e1a \u0e40\u0e2d\u0e37\u0e49\u0e2d\u0e40\u0e1f\u0e37\u0e49\u0e2d\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48 \u0e2d\u0e33\u0e19\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e14\u0e27\u0e01\u0e14\u0e49\u0e32\u0e19\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e25\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e33\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e08\u0e32\u0e01\u0e1e\u0e37\u0e0a\u0e1c\u0e31\u0e01\u0e1b\u0e25\u0e2d\u0e14\u0e2a\u0e32\u0e23\u0e1e\u0e34\u0e29\u0e43\u0e2b\u0e49\u0e1e\u0e27\u0e01\u0e40\u0e23\u0e32\u0e44\u0e14\u0e49\u0e17\u0e32\u0e19\u0e01\u0e31\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e14\u0e35 @ Tree Eco Working Space (\u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e23\u0e32\u0e21\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e32 \u0e16\u0e19\u0e19\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e32) \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e43\u0e19\u0e04\u0e23\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e04\u0e48\u0e30<\/p>","protected":false},"author":1,"featured_media":11391,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[55],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.terabyteplus.com\/en\/wp-json\/wp\/v2\/posts\/11366"}],"collection":[{"href":"https:\/\/www.terabyteplus.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.terabyteplus.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.terabyteplus.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.terabyteplus.com\/en\/wp-json\/wp\/v2\/comments?post=11366"}],"version-history":[{"count":14,"href":"https:\/\/www.terabyteplus.com\/en\/wp-json\/wp\/v2\/posts\/11366\/revisions"}],"predecessor-version":[{"id":11400,"href":"https:\/\/www.terabyteplus.com\/en\/wp-json\/wp\/v2\/posts\/11366\/revisions\/11400"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.terabyteplus.com\/en\/wp-json\/wp\/v2\/media\/11391"}],"wp:attachment":[{"href":"https:\/\/www.terabyteplus.com\/en\/wp-json\/wp\/v2\/media?parent=11366"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.terabyteplus.com\/en\/wp-json\/wp\/v2\/categories?post=11366"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.terabyteplus.com\/en\/wp-json\/wp\/v2\/tags?post=11366"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}